{"id":581,"count":22,"description":"","link":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/category\/incident\/discipline\/","name":"\u4e8b\u4ef6\u30fb\u61f2\u6212","slug":"discipline","taxonomy":"category","parent":579,"meta":[],"z_taxonomy_image_url":"https:\/\/kaigodatebase.com\/wp-content\/uploads\/2022\/07\/\u753b\u50cf2-1.png","_links":{"self":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/categories\/581"}],"collection":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/categories\/579"}],"wp:post_type":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts?categories=581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}