{"id":20400,"date":"2021-12-22T10:14:24","date_gmt":"2021-12-22T01:14:24","guid":{"rendered":"http:\/\/kaigodatebase.com\/?p=20400"},"modified":"2021-12-22T10:14:24","modified_gmt":"2021-12-22T01:14:24","slug":"%e7%b5%b1%e8%a8%88%ef%bc%9a2019%e5%b9%b4%e5%81%a5%e5%ba%b7%e5%af%bf%e5%91%bd%e3%80%80%e7%94%b7%e6%80%a772-68%e6%ad%b3%e3%80%80%e5%a5%b3%e6%80%a775-38%e6%ad%b3%e3%80%80%e5%8e%9a%e7%94%9f%e5%8a%b4","status":"publish","type":"post","link":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/statistical-data\/20400\/","title":{"rendered":"\u7d71\u8a08\uff1a2019\u5e74\u5065\u5eb7\u5bff\u547d\u3000\u7537\u602772.68\u6b73\u3000\u5973\u602775.38\u6b73\u3000\u539a\u751f\u52b4\u50cd\u7701"},"content":{"rendered":"<p><strong>2021\u5e7412\u670822\u65e5\uff08\u7d71\u8a08\uff09<\/strong><\/p>\n<p>\u30fb2021\u5e7412\u670820\u65e5\u3001\u539a\u751f\u52b4\u50cd\u7701\u767a\u8868\u306e2019\u5e74\u5065\u5eb7\u5bff\u547d<\/p>\n<p>\u30fb\u7d0468\u4e078000\u4eba\u3092\u5bfe\u8c61\u3068\u3057\u305f\u56fd\u6c11\u751f\u6d3b\u57fa\u790e\u8abf\u67fb\u3092\u57fa\u306b\u63a8\u8a08<\/p>\n<p>\u30fb2019\u5e74\u3000\u7537\u6027\u300072.68\u6b73\u3001\u5973\u6027\u300075.38\u6b73<\/p>\n<p>\u30fb\u524d\u56de\u8abf\u67fb\u306e2016\u5e74\u3000\u7537\u6027\u300072.14\u6b73\u3001\u5973\u6027\u300074.79\u6b73<\/p>\n<p>\u30fb\u7537\u60271\u4f4d\u3000\u5927\u5206\u770c\u300073.72\u6b73<\/p>\n<p>\u30fb\u5973\u60271\u4f4d\u3000\u4e09\u91cd\u770c\u300077.58\u6b73<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2021\u5e7412\u670822\u65e5\uff08\u7d71\u8a08\uff09 \u30fb2021\u5e7412\u670820\u65e5\u3001\u539a\u751f\u52b4\u50cd\u7701\u767a\u8868\u306e2019\u5e74\u5065\u5eb7\u5bff\u547d \u30fb\u7d0468\u4e078000\u4eba\u3092\u5bfe\u8c61\u3068\u3057\u305f\u56fd\u6c11\u751f\u6d3b\u57fa\u790e\u8abf\u67fb\u3092\u57fa\u306b\u63a8\u8a08 \u30fb20\u2026<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts\/20400"}],"collection":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/comments?post=20400"}],"version-history":[{"count":1,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts\/20400\/revisions"}],"predecessor-version":[{"id":20401,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts\/20400\/revisions\/20401"}],"wp:attachment":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/media?parent=20400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/categories?post=20400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/tags?post=20400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}