{"id":311,"date":"2018-03-06T00:18:49","date_gmt":"2018-03-05T15:18:49","guid":{"rendered":"http:\/\/kaigodatebase.com\/?p=311"},"modified":"2019-08-17T00:23:31","modified_gmt":"2019-08-16T15:23:31","slug":"%e7%b5%b1%e8%a8%88%e3%83%87%e3%83%bc%e3%82%bf%e3%83%bb%e4%b8%8d%e6%ad%a3%e8%ab%8b%e6%b1%82%e3%83%bb%e6%8c%87%e5%ae%9a%e5%8f%96%e6%b6%88%ef%bc%9a%e5%8e%9a%e7%94%9f%e5%8a%b4%e5%83%8d%e7%9c%81%e3%80%80","status":"publish","type":"post","link":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/statistical-data\/311\/","title":{"rendered":"\u7d71\u8a08\u30c7\u30fc\u30bf\u30fb\u4e0d\u6b63\u8acb\u6c42\u30fb\u6307\u5b9a\u53d6\u6d88\uff1a\u539a\u751f\u52b4\u50cd\u7701\u3000\u653f\u7b56\u8aac\u660e\u4f1a\u30002016\u5e74\u5ea6\u3000\u6307\u5b9a\u53d6\u6d88\u30fb\u52b9\u529b\u306e\u505c\u6b62244\u4ef6"},"content":{"rendered":"<p><strong>2018\u5e743\u67086\u65e5\uff08\u7d71\u8a08\u30c7\u30fc\u30bf\u30fb\u4e0d\u6b63\u8acb\u6c42\u30fb\u6307\u5b9a\u53d6\u6d88\uff09<\/strong><\/p>\n<p>\u30fb\u539a\u751f\u52b4\u50cd\u7701\u3000\u653f\u7b56\u8aac\u660e\u4f1a<br \/>\n\u30fb2016\u5e74\u5ea6\u306e1\u5e74\u9593<br \/>\n\u30fb\u4f55\u3089\u304b\u306e\u4e0d\u6b63\u306b\u3088\u3063\u3066\u6307\u5b9a\u306e\u53d6\u308a\u6d88\u3057\u3084\u52b9\u529b\u306e\u505c\u6b62\u3068\u3044\u3063\u305f\u51e6\u5206\u3092\u53d7\u3051\u305f\u4ecb\u8b77\u65bd\u8a2d\u30fb\u4e8b\u696d\u6240\u304c244\u4ef6<br \/>\n\u30fb\u6307\u5b9a\u306e\u53d6\u308a\u6d88\u3057\u304c141\u4ef6\u3001\u6307\u5b9a\u306e\u52b9\u529b\u505c\u6b62\u304c103\u4ef6<br \/>\n\u30fb\u55b6\u5229\u6cd5\u4eba\u304c206\u4ef6<br \/>\n\u30fb\u8a2a\u554f\u4ecb\u8b7784\u4ef6\u3001\u5c45\u5b85\u4ecb\u8b77\u652f\u63f438\u4ef6\u3001\u901a\u6240\u4ecb\u8b7734\u4ef6\u3001\u30b0\u30eb\u30fc\u30d7\u30db\u30fc\u30e013\u4ef6<br \/>\n\u30fb\u53d6\u308a\u6d88\u3057\u306b\u81f3\u3063\u305f\u7406\u7531\uff08\u91cd\u8907\u3042\u308a\uff09\u3001\u4e0d\u6b63\u8acb\u6c4259.6%\u3001\u6cd5\u4ee4\u9055\u53cd25.5%\u3001\u865a\u507d\u5831\u544a25.5%\u3067\u7d9a\u3044\u305f<br \/>\n\u30fb\u52b9\u529b\u505c\u6b62\u306e\u7406\u7531\u3001\u4e0d\u6b63\u8acb\u6c4240.8%\u3001\u6cd5\u4ee4\u9055\u53cd27.5%\u3001\u865a\u507d\u5831\u544a22.3%<br \/>\n\u30fb\u6cd5\u4eba\u5168\u4f53\u3067\u95a2\u4e0e\u304c\u7121\u304b\u3063\u305f\u304b\u306a\u3069\u3092\u8abf\u3079\u308b\u7279\u5225\u691c\u67fb68\u4ef6\uff08\u3046\u3061\u6539\u5584\u52e7\u544a29\u4ef6\u3001\u6539\u5584\u547d\u4ee44\u4ef6\uff09<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2018\u5e743\u67086\u65e5\uff08\u7d71\u8a08\u30c7\u30fc\u30bf\u30fb\u4e0d\u6b63\u8acb\u6c42\u30fb\u6307\u5b9a\u53d6\u6d88\uff09 \u30fb\u539a\u751f\u52b4\u50cd\u7701\u3000\u653f\u7b56\u8aac\u660e\u4f1a \u30fb2016\u5e74\u5ea6\u306e1\u5e74\u9593 \u30fb\u4f55\u3089\u304b\u306e\u4e0d\u6b63\u306b\u3088\u3063\u3066\u6307\u5b9a\u306e\u53d6\u308a\u6d88\u3057\u3084\u52b9\u529b\u306e\u505c\u6b62\u3068\u3044\u3063\u305f\u2026<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,7,17],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts\/311"}],"collection":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/comments?post=311"}],"version-history":[{"count":3,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts\/311\/revisions"}],"predecessor-version":[{"id":316,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts\/311\/revisions\/316"}],"wp:attachment":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/media?parent=311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/categories?post=311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/tags?post=311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}