{"id":35174,"date":"2024-03-19T18:58:07","date_gmt":"2024-03-19T09:58:07","guid":{"rendered":"https:\/\/kaigodatebase.com\/?p=35174"},"modified":"2024-03-19T18:58:07","modified_gmt":"2024-03-19T09:58:07","slug":"%e4%bb%8b%e8%ad%b7%e4%bf%9d%e9%99%ba%e6%9c%80%e6%96%b0%e6%83%85%e5%a0%b1vol-1032%e3%80%8c%e9%81%a9%e5%88%87%e3%81%aa%e3%82%b1%e3%82%a2%e3%83%9e%e3%83%8d%e3%82%b8%e3%83%a1%e3%83%b3%e3%83%88-100-2-2-276","status":"publish","type":"post","link":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/outbreak\/35174\/","title":{"rendered":"\u5c71\u53e3\u770c\u3001\u5b87\u90e8\u5e02\u306e\u65bd\u8a2d\u3067\u611f\u67d3\u6027\u80c3\u8178\u708e\u304c\u96c6\u56e3\u767a\u751f"},"content":{"rendered":"<p><strong>2024\u5e743\u670819<\/strong><strong>\u65e5<\/strong><\/p>\n<p>\u30fb\u5b87\u90e8\u5e02\u306e\u9ad8\u9f62\u8005\u65bd\u8a2d\u3067\u3001\u5165\u5c45\u800543\u4eba\u3068\u8077\u54e14\u4eba\u304c\u611f\u67d3\u6027\u80c3\u8178\u708e\u306b\u3088\u308b\u4e0b\u75e2\u3084\u5614\u5410\u306e\u75c7\u72b6\u3092\u5831\u544a\u3002<\/p>\n<p>\u30fb3\u670810\u65e5\u304b\u308918\u65e5\u306b\u304b\u3051\u3066\u306e\u767a\u751f\u3067\u3001\u5b87\u90e8\u74b0\u5883\u4fdd\u5065\u6240\u304c\u885b\u751f\u6307\u5c0e\u3068\u6d88\u6bd2\u3092\u5b9f\u65bd\u3002<\/p>\n<p>\u30fb\u611f\u67d3\u6027\u80c3\u8178\u708e\u306f\u3001\u98df\u54c1\u3084\u4fbf\u3092\u4ecb\u3057\u305f\u30a6\u30a4\u30eb\u30b9\u3084\u7d30\u83cc\u306b\u3088\u308b\u611f\u67d3\u304c\u539f\u56e0\u3002<\/p>\n<p>\u30fb\u7279\u306b\u4e73\u5e7c\u5150\u3084\u9ad8\u9f62\u8005\u306b\u91cd\u75c7\u5316\u306e\u30ea\u30b9\u30af\u304c\u3042\u308a\u3001\u770c\u306f\u624b\u6d17\u3044\u3084\u8abf\u7406\u5668\u5177\u306e\u6bba\u83cc\u3092\u5fb9\u5e95\u3059\u308b\u3088\u3046\u547c\u3073\u304b\u3051\u3066\u3044\u308b\u3002<\/p>\n<p>\u30fb\u4eca\u5e74\u5ea6\u3001\u5b87\u90e8\u5e02\u3067\u611f\u67d3\u6027\u80c3\u8178\u708e\u306e\u96c6\u56e3\u767a\u751f\u306f\u3053\u308c\u30673\u4ef6\u76ee\u3002<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.personalassist.co.jp\/kaigodatabase\/\">\u4ecb\u8b77\u30c7\u30fc\u30bf\u30d9\u30fc\u30b9<\/a><br \/>\n\u4ecb\u8b77\u696d\u754c\u306e\u69d8\u3005\u306a\u60c5\u5831\u3092\u307e\u3068\u3081\u305f\u30c7\u30fc\u30bf\u30d9\u30fc\u30b9<br \/>\n<a href=\"https:\/\/iryoaround.com\/\">\u533b\u7642\u30a2\u30e9\u30a6\u30f3\u30c9<\/a><br \/>\n\u533b\u7642\u696d\u754c\u306e\u69d8\u3005\u306a\u60c5\u5831\u3092\u307e\u3068\u3081\u305f\u30c7\u30fc\u30bf\u30d9\u30fc\u30b9<br \/>\n<a href=\"https:\/\/okusuritimes.com\/\">\u304a\u85ac\u30bf\u30a4\u30e0\u30ba<\/a><br \/>\n\u304a\u85ac\u306e\u69d8\u3005\u306a\u60c5\u5831\u3092\u307e\u3068\u3081\u305f\u30c7\u30fc\u30bf\u30d9\u30fc\u30b9<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2024\u5e743\u670819\u65e5 \u30fb\u5b87\u90e8\u5e02\u306e\u9ad8\u9f62\u8005\u65bd\u8a2d\u3067\u3001\u5165\u5c45\u800543\u4eba\u3068\u8077\u54e14\u4eba\u304c\u611f\u67d3\u6027\u80c3\u8178\u708e\u306b\u3088\u308b\u4e0b\u75e2\u3084\u5614\u5410\u306e\u75c7\u72b6\u3092\u5831\u544a\u3002 \u30fb3\u670810\u65e5\u304b\u308918\u65e5\u306b\u304b\u3051\u3066\u306e\u767a\u751f\u3067\u3001\u5b87\u90e8\u74b0\u2026<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts\/35174"}],"collection":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/comments?post=35174"}],"version-history":[{"count":1,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts\/35174\/revisions"}],"predecessor-version":[{"id":35175,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts\/35174\/revisions\/35175"}],"wp:attachment":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/media?parent=35174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/categories?post=35174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/tags?post=35174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}