{"id":35176,"date":"2024-03-19T19:00:56","date_gmt":"2024-03-19T10:00:56","guid":{"rendered":"https:\/\/kaigodatebase.com\/?p=35176"},"modified":"2024-03-19T19:00:56","modified_gmt":"2024-03-19T10:00:56","slug":"%e4%bb%8b%e8%ad%b7%e4%bf%9d%e9%99%ba%e6%9c%80%e6%96%b0%e6%83%85%e5%a0%b1vol-1032%e3%80%8c%e9%81%a9%e5%88%87%e3%81%aa%e3%82%b1%e3%82%a2%e3%83%9e%e3%83%8d%e3%82%b8%e3%83%a1%e3%83%b3%e3%83%88-100-2-2-277","status":"publish","type":"post","link":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/outbreak\/35176\/","title":{"rendered":"\u5ca9\u624b\u770c\u3001\u5965\u5dde\u4fdd\u5065\u6240\u7ba1\u5185\u3067\u30ce\u30ed\u30a6\u30a4\u30eb\u30b9\u96c6\u56e3\u611f\u67d3"},"content":{"rendered":"<p><strong>2024\u5e743\u670819<\/strong><strong>\u65e5<\/strong><\/p>\n<p>\u30fb\u5ca9\u624b\u770c\u304c\u5965\u5dde\u4fdd\u5065\u6240\u7ba1\u5185\u306e\u9ad8\u9f62\u8005\u65bd\u8a2d\u3067\u30ce\u30ed\u30a6\u30a4\u30eb\u30b9\u306b\u3088\u308b\u611f\u67d3\u6027\u80c3\u8178\u708e\u306e\u96c6\u56e3\u767a\u751f\u3092\u5831\u544a\u3002<\/p>\n<p>\u30fb3\u67088\u65e5\u304b\u308913\u65e5\u306b\u304b\u3051\u3066\u3001\u5229\u7528\u800514\u4eba\u3068\u8077\u54e13\u4eba\u306e\u8a0817\u4eba\u304c\u5614\u5410\u3084\u4e0b\u75e2\u306e\u75c7\u72b6\u3092\u8a34\u3048\u305f\u3002<\/p>\n<p>\u30fb\u4fdd\u5065\u6240\u306e\u8abf\u67fb\u3067\u3001\u75c7\u72b6\u306e\u3042\u308b7\u4eba\u304b\u3089\u30ce\u30ed\u30a6\u30a4\u30eb\u30b9\u304c\u691c\u51fa\u3055\u308c\u308b\u3002<\/p>\n<p>\u30fb\u91cd\u75c7\u8005\u306f\u304a\u3089\u305a\u3001\u611f\u67d3\u3057\u305f\u5168\u54e1\u304c\u56de\u5fa9\u50be\u5411\u306b\u3042\u308b\u3002<\/p>\n<p>\u30fb\u5ca9\u624b\u770c\u306f\u3001\u611f\u67d3\u62e1\u5927\u9632\u6b62\u306e\u305f\u3081\u306b\u624b\u6d17\u3044\u3001\u63db\u6c17\u3001\u6d88\u6bd2\u306a\u3069\u306e\u5bfe\u7b56\u3092\u5fb9\u5e95\u3059\u308b\u3088\u3046\u547c\u3073\u304b\u3051\u3066\u3044\u308b\u3002<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.personalassist.co.jp\/kaigodatabase\/\">\u4ecb\u8b77\u30c7\u30fc\u30bf\u30d9\u30fc\u30b9<\/a><br \/>\n\u4ecb\u8b77\u696d\u754c\u306e\u69d8\u3005\u306a\u60c5\u5831\u3092\u307e\u3068\u3081\u305f\u30c7\u30fc\u30bf\u30d9\u30fc\u30b9<br \/>\n<a href=\"https:\/\/iryoaround.com\/\">\u533b\u7642\u30a2\u30e9\u30a6\u30f3\u30c9<\/a><br \/>\n\u533b\u7642\u696d\u754c\u306e\u69d8\u3005\u306a\u60c5\u5831\u3092\u307e\u3068\u3081\u305f\u30c7\u30fc\u30bf\u30d9\u30fc\u30b9<br \/>\n<a href=\"https:\/\/okusuritimes.com\/\">\u304a\u85ac\u30bf\u30a4\u30e0\u30ba<\/a><br \/>\n\u304a\u85ac\u306e\u69d8\u3005\u306a\u60c5\u5831\u3092\u307e\u3068\u3081\u305f\u30c7\u30fc\u30bf\u30d9\u30fc\u30b9<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2024\u5e743\u670819\u65e5 \u30fb\u5ca9\u624b\u770c\u304c\u5965\u5dde\u4fdd\u5065\u6240\u7ba1\u5185\u306e\u9ad8\u9f62\u8005\u65bd\u8a2d\u3067\u30ce\u30ed\u30a6\u30a4\u30eb\u30b9\u306b\u3088\u308b\u611f\u67d3\u6027\u80c3\u8178\u708e\u306e\u96c6\u56e3\u767a\u751f\u3092\u5831\u544a\u3002 \u30fb3\u67088\u65e5\u304b\u308913\u65e5\u306b\u304b\u3051\u3066\u3001\u5229\u7528\u800514\u4eba\u3068\u8077\u54e13\u2026<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts\/35176"}],"collection":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/comments?post=35176"}],"version-history":[{"count":1,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts\/35176\/revisions"}],"predecessor-version":[{"id":35177,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts\/35176\/revisions\/35177"}],"wp:attachment":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/media?parent=35176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/categories?post=35176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/tags?post=35176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}