{"id":37101,"date":"2024-07-24T08:42:55","date_gmt":"2024-07-23T23:42:55","guid":{"rendered":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/?p=37101"},"modified":"2024-07-24T08:48:00","modified_gmt":"2024-07-23T23:48:00","slug":"%e4%bb%8b%e8%ad%b7%e4%bf%9d%e9%99%ba%e6%9c%80%e6%96%b0%e6%83%85%e5%a0%b1vol-1032%e3%80%8c%e9%81%a9%e5%88%87%e3%81%aa%e3%82%b1%e3%82%a2%e3%83%9e%e3%83%8d%e3%82%b8%e3%83%a1%e3%83%b3%e3%83%88-100-2-10-65","status":"publish","type":"post","link":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/statistical-data\/37101\/","title":{"rendered":"\u4ecb\u8b77\u4e8b\u696d\u8005\u306e\u5012\u7523\u3001\u904e\u53bb\u6700\u591a\u306e80\u4ef6\u8d85"},"content":{"rendered":"<p><strong>2024\u5e747\u670823\u65e5<\/strong><\/p>\n<p>\u30fb2024\u5e74\u4e0a\u534a\u671f\u306b\u5012\u7523\u3057\u305f\u4ecb\u8b77\u4e8b\u696d\u8005\u304c80\u4ef6\u3092\u8d85\u3048\u3001\u904e\u53bb\u6700\u591a\u3068\u306a\u3063\u305f\u3002<br \/>\n\u30fb\u5831\u916c\u6539\u5b9a\u306a\u3069\u306e\u5f71\u97ff\u3067\u3001\u4eca\u5f8c\u3082\u5012\u7523\u306f\u5897\u52a0\u3059\u308b\u3068\u4e88\u6e2c\u3055\u308c\u3066\u3044\u308b\u3002<br \/>\n\u30fb1\uff5e6\u6708\u306e\u5012\u7523\u4ef6\u6570\u306f\u524d\u5e74\u6bd41.5\u500d\u306e81\u4ef6\u3067\u3001\u904e\u53bb\u6700\u591a\u3092\u8a18\u9332\u3002<br \/>\n\u30fb\u696d\u7a2e\u5225\u3067\u306f\u8a2a\u554f\u4ecb\u8b77\u304c40\u4ef6\u3067\u6700\u591a\u3001\u6b21\u3044\u3067\u901a\u6240\u30fb\u77ed\u671f\u5165\u6240\u304c25\u4ef6\u3001\u6709\u6599\u8001\u4eba\u30db\u30fc\u30e0\u304c9\u4ef6\u3002<br \/>\n\u30fb\u5012\u7523\u539f\u56e0\u306f\u5229\u7528\u8005\u7372\u5f97\u306e\u96e3\u3057\u3055\u306b\u3088\u308b\u58f2\u308a\u4e0a\u3052\u4e0d\u632f\u304c64\u4ef6\u3067\u6700\u591a\u3002<br \/>\n\u30fb\u90fd\u9053\u5e9c\u770c\u5225\u3067\u306f\u5927\u962a\u304c11\u4ef6\u3067\u6700\u591a\u3001\u6b21\u3044\u3067\u6771\u4eac\u304c6\u4ef6\u3001\u795e\u5948\u5ddd\u304c5\u4ef6\u3002<br \/>\n\u30fb\u5f93\u696d\u54e1\u6570\u5225\u3067\u306f5\u4eba\u672a\u6e80\u306e\u5c0f\u898f\u6a21\u4e8b\u696d\u8005\u304c47\u4ef6\u3067\u5168\u4f53\u306e6\u5272\u3092\u5360\u3081\u308b\u3002<br \/>\n\u30fb\u8ca0\u50b5\u984d\u5225\u3067\u306f1\u5104\u5186\u672a\u6e80\u304c61\u4ef6\u30011\u5104\u5186\u4ee5\u4e0a\u304c20\u4ef6\u3002<br \/>\n\u30fb2024\u5e74\u5ea6\u306e\u4ecb\u8b77\u5831\u916c\u6539\u5b9a\u306f\u30d7\u30e9\u30b91.59\uff05\u3001\u4ecb\u8b77\u8077\u54e1\u306e\u51e6\u9047\u6539\u5584\u306f2.5\uff05\u3002<br \/>\n\u30fb\u8a2a\u554f\u4ecb\u8b77\u306e\u57fa\u672c\u5831\u916c\u306f\u4e0b\u304c\u308b\u7d50\u679c\u306b \u30fb\u4ed6\u696d\u7a2e\u3067\u306e\u8cc3\u4e0a\u3052\u52a0\u901f\u3084\u4eba\u624b\u4e0d\u8db3\u3001\u7269\u4fa1\u9ad8\u306e\u5f71\u97ff\u3067\u5012\u7523\u306f\u5897\u52a0\u50be\u5411\u306b\u3042\u308b\u3002<\/p>\n<p><a href=\"https:\/\/www.personalassist.co.jp\/kaigodatabase\/\">\u4ecb\u8b77\u30c7\u30fc\u30bf\u30d9\u30fc\u30b9<\/a><br \/>\n\u4ecb\u8b77\u696d\u754c\u306e\u69d8\u3005\u306a\u60c5\u5831\u3092\u307e\u3068\u3081\u305f\u30c7\u30fc\u30bf\u30d9\u30fc\u30b9<br \/>\n<a href=\"https:\/\/www.personalassist.co.jp\/iryoaround\/\">\u533b\u7642\u30a2\u30e9\u30a6\u30f3\u30c9<\/a><br \/>\n\u533b\u7642\u696d\u754c\u306e\u69d8\u3005\u306a\u60c5\u5831\u3092\u307e\u3068\u3081\u305f\u30c7\u30fc\u30bf\u30d9\u30fc\u30b9<br \/>\n<a href=\"https:\/\/www.personalassist.co.jp\/okusuritimes\/\">\u304a\u85ac\u30bf\u30a4\u30e0\u30ba<\/a><br \/>\n\u304a\u85ac\u306e\u69d8\u3005\u306a\u60c5\u5831\u3092\u307e\u3068\u3081\u305f\u30c7\u30fc\u30bf\u30d9\u30fc\u30b9<\/p>\n<p><a href=\"https:\/\/www.personalassist.co.jp\/\">\u30d1\u30fc\u30bd\u30ca\u30eb\u30a2\u30b7\u30b9\u30c8<\/a><br \/>\n\u533b\u5e2b\u6c42\u4eba\u3001\u770b\u8b77\u5e2b\u6c42\u4eba\u3001\u85ac\u5264\u5e2b\u6c42\u4eba \u3092\u306f\u3058\u3081\u533b\u7642\u4eba\u6750\u306a\u3089\u30d1\u30fc\u30bd\u30ca\u30eb\u30a2\u30b7\u30b9\u30c8<br \/>\n<a href=\"https:\/\/www.personalassist.co.jp\/hojokin\/\">\u88dc\u52a9\u91d1\u52a9\u6210\u91d1\u60c5\u5831<\/a><br \/>\n\u533b\u7642\u6a5f\u95a2\u3068\u305d\u306e\u652f\u63f4\u8005\u306e\u305f\u3081\u306e\u60c5\u5831\u30b5\u30a4\u30c8<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2024\u5e747\u670823\u65e5 \u30fb2024\u5e74\u4e0a\u534a\u671f\u306b\u5012\u7523\u3057\u305f\u4ecb\u8b77\u4e8b\u696d\u8005\u304c80\u4ef6\u3092\u8d85\u3048\u3001\u904e\u53bb\u6700\u591a\u3068\u306a\u3063\u305f\u3002 \u30fb\u5831\u916c\u6539\u5b9a\u306a\u3069\u306e\u5f71\u97ff\u3067\u3001\u4eca\u5f8c\u3082\u5012\u7523\u306f\u5897\u52a0\u3059\u308b\u3068\u4e88\u6e2c\u3055\u308c\u3066\u3044\u308b\u3002 \u2026<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,4],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts\/37101"}],"collection":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/comments?post=37101"}],"version-history":[{"count":3,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts\/37101\/revisions"}],"predecessor-version":[{"id":37106,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts\/37101\/revisions\/37106"}],"wp:attachment":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/media?parent=37101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/categories?post=37101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/tags?post=37101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}