{"id":37395,"date":"2024-08-07T08:14:35","date_gmt":"2024-08-06T23:14:35","guid":{"rendered":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/?p=37395"},"modified":"2024-08-07T08:14:35","modified_gmt":"2024-08-06T23:14:35","slug":"%e4%bb%8b%e8%ad%b7%e4%bf%9d%e9%99%ba%e6%9c%80%e6%96%b0%e6%83%85%e5%a0%b1vol-1032%e3%80%8c%e9%81%a9%e5%88%87%e3%81%aa%e3%82%b1%e3%82%a2%e3%83%9e%e3%83%8d%e3%82%b8%e3%83%a1%e3%83%b3%e3%83%88-100-2-1-38","status":"publish","type":"post","link":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/statistical-data\/37395\/","title":{"rendered":"\u731b\u6691\u306b\u3088\u308b\u71b1\u4e2d\u75c7\u642c\u9001\u8005\u6570\u30012\u9031\u9023\u7d9a\u30671\u4e07\u4eba\u8d85\u3048"},"content":{"rendered":"<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-17743\" src=\"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-content\/uploads\/2021\/05\/img-statistical-data.jpg\" alt=\"\" width=\"100\" height=\"100\" \/><br \/>\n2024\u5e748\u67086\u65e5<\/strong><\/p>\n<p>\u30fb\u7dcf\u52d9\u7701\u6d88\u9632\u5e81\u304c\u767a\u8868\u3057\u305f\u30c7\u30fc\u30bf\u306b\u3088\u308b\u3068\u30017\u670829\u65e5\u304b\u30898\u67084\u65e5\u307e\u3067\u306e1\u9031\u9593\u306b\u71b1\u4e2d\u75c7\u3067\u6551\u6025\u642c\u9001\u3055\u308c\u305f\u4eba\u306f1\u4e072272\u4eba\u306b\u4e0a\u3063\u305f\u3002<br \/>\n\u30fb\u4eca\u5e744\u670829\u65e5\u306e\u8abf\u67fb\u958b\u59cb\u4ee5\u6765\u3001\u6700\u591a\u642c\u9001\u8005\u6570\u3092\u8a18\u9332\u3057\u305f\u524d\u9031\u304b\u3089400\u4eba\u6e1b\u5c11\u3057\u305f\u304c\u300135\u5ea6\u4ee5\u4e0a\u306e\u9ad8\u6e29\u304c\u7d9a\u3044\u305f\u305f\u3081\u3001\u642c\u9001\u8005\u6570\u306f\u4f9d\u7136\u3068\u3057\u30661\u4e07\u4eba\u3092\u8d85\u3048\u3066\u3044\u308b\u3002<br \/>\n\u30fb65\u6b73\u4ee5\u4e0a\u306e\u9ad8\u9f62\u8005\u304c\u642c\u9001\u8005\u5168\u4f53\u306e60%\u3092\u5360\u3081\u30017395\u4eba\u304c\u71b1\u4e2d\u75c7\u3067\u6551\u6025\u642c\u9001\u3055\u308c\u305f\u3002<br \/>\n\u30fb\u71b1\u4e2d\u75c7\u306b\u3088\u308b\u6b7b\u8005\u306f21\u4eba\u30013\u9031\u9593\u4ee5\u4e0a\u306e\u5165\u9662\u304c\u5fc5\u8981\u306a\u91cd\u75c7\u8005\u306f386\u4eba\u3060\u3063\u305f\u3002<br \/>\n\u30fb\u71b1\u4e2d\u75c7\u306e\u767a\u751f\u5834\u6240\u3068\u3057\u3066\u306f\u3001\u81ea\u5b85\u3084\u4f4f\u5c45\u304c5111\u4eba\u3067\u6700\u3082\u591a\u304f\u3001\u6b21\u3044\u3067\u9053\u8def\u3067\u306e\u767a\u751f\u304c2287\u4eba\u3060\u3063\u305f\u3002\u3002<\/p>\n<p><a href=\"https:\/\/www.personalassist.co.jp\/kaigodatabase\/\">\u4ecb\u8b77\u30c7\u30fc\u30bf\u30d9\u30fc\u30b9<\/a><br \/>\n\u4ecb\u8b77\u696d\u754c\u306e\u69d8\u3005\u306a\u60c5\u5831\u3092\u307e\u3068\u3081\u305f\u30c7\u30fc\u30bf\u30d9\u30fc\u30b9<br \/>\n<a href=\"https:\/\/www.personalassist.co.jp\/iryoaround\/\">\u533b\u7642\u30a2\u30e9\u30a6\u30f3\u30c9<\/a><br \/>\n\u533b\u7642\u696d\u754c\u306e\u69d8\u3005\u306a\u60c5\u5831\u3092\u307e\u3068\u3081\u305f\u30c7\u30fc\u30bf\u30d9\u30fc\u30b9<br \/>\n<a href=\"https:\/\/www.personalassist.co.jp\/okusuritimes\/\">\u304a\u85ac\u30bf\u30a4\u30e0\u30ba<\/a><br \/>\n\u304a\u85ac\u306e\u69d8\u3005\u306a\u60c5\u5831\u3092\u307e\u3068\u3081\u305f\u30c7\u30fc\u30bf\u30d9\u30fc\u30b9<\/p>\n<p><a href=\"https:\/\/www.personalassist.co.jp\/\">\u30d1\u30fc\u30bd\u30ca\u30eb\u30a2\u30b7\u30b9\u30c8<\/a><br \/>\n\u533b\u5e2b\u6c42\u4eba\u3001\u770b\u8b77\u5e2b\u6c42\u4eba\u3001\u85ac\u5264\u5e2b\u6c42\u4eba \u3092\u306f\u3058\u3081\u533b\u7642\u4eba\u6750\u306a\u3089\u30d1\u30fc\u30bd\u30ca\u30eb\u30a2\u30b7\u30b9\u30c8<br \/>\n<a href=\"https:\/\/www.personalassist.co.jp\/hojokin\/\">\u88dc\u52a9\u91d1\u52a9\u6210\u91d1\u60c5\u5831<\/a><br \/>\n\u533b\u7642\u6a5f\u95a2\u3068\u305d\u306e\u652f\u63f4\u8005\u306e\u305f\u3081\u306e\u60c5\u5831\u30b5\u30a4\u30c8<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2024\u5e748\u67086\u65e5 \u30fb\u7dcf\u52d9\u7701\u6d88\u9632\u5e81\u304c\u767a\u8868\u3057\u305f\u30c7\u30fc\u30bf\u306b\u3088\u308b\u3068\u30017\u670829\u65e5\u304b\u30898\u67084\u65e5\u307e\u3067\u306e1\u9031\u9593\u306b\u71b1\u4e2d\u75c7\u3067\u6551\u6025\u642c\u9001\u3055\u308c\u305f\u4eba\u306f1\u4e072272\u4eba\u306b\u4e0a\u3063\u305f\u3002 \u30fb\u4eca\u5e744\u67082\u2026<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts\/37395"}],"collection":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/comments?post=37395"}],"version-history":[{"count":2,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts\/37395\/revisions"}],"predecessor-version":[{"id":37397,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/posts\/37395\/revisions\/37397"}],"wp:attachment":[{"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/media?parent=37395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/categories?post=37395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.personalassist.co.jp\/kaigodatabase\/wp-json\/wp\/v2\/tags?post=37395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}